{"id":9683,"date":"2020-12-07T12:46:25","date_gmt":"2020-12-07T11:46:25","guid":{"rendered":"https:\/\/www.hondadreams.es\/?p=9683"},"modified":"2020-12-07T12:46:25","modified_gmt":"2020-12-07T11:46:25","slug":"albon-termina-sexto-en-un-segundo-y-caotico-gran-premio-de-f1-en-barein","status":"publish","type":"post","link":"https:\/\/www.honda.es\/hondadreams\/2020\/12\/07\/albon-termina-sexto-en-un-segundo-y-caotico-gran-premio-de-f1-en-barein\/","title":{"rendered":"Albon termina sexto en un segundo y ca\u00f3tico Gran Premio de F1 en Bar\u00e9in"},"content":{"rendered":"<p>El piloto de Red Bull Alex Albon consigui\u00f3 cruzar la meta en sexto lugar y llevarse un pu\u00f1ado de puntos en un loco GP de Sakhir en Bar\u00e9in. Un espect\u00e1culo imprevisible lleno de sorpresas, inclu\u00edda la retirada del otro Red Bull, Max Verstappen, y del AlphaTauri Pierre Gasly, los dos en la primera vuelta. Sin duda una de las carreras m\u00e1s emocionantes de la temporada.<\/p>\n<p>Segundo fin de semana de competici\u00f3n en el Circuito Internacional de Bar\u00e9in para la categor\u00eda reina, esta vez con un trazado alternativo en el circuito para celebrar el GP de Sakhir. Como la semana pasada, la primera vuelta fue todo un espect\u00e1culo. Eso s\u00ed, esta vez las sorpresas no fueron de la misma magnitud que el impactante accidente del piloto de Haas Romain Grosjean la semana pasada, uno de los m\u00e1s violentos de las \u00faltimas d\u00e9cadas. La configuraci\u00f3n alternativa del circuito auguraba una carrera corta, de s\u00f3lo 3.5 km.<\/p>\n<p>A pesar de las dos banderas rojas y las tres consiguientes salidas, Albon supo mantener la compostura. Despu\u00e9s de la segunda ronda de paradas, el tailand\u00e9s, que hab\u00eda salido desde la duod\u00e9cima posici\u00f3n, ya iba sexto. Tambi\u00e9n tuvo un buen d\u00eda el otro piloto de la Scuderia AlphaTauri Daniil Kvyat, que finaliz\u00f3 s\u00e9ptimo. Los dos monoplazas terminaron la carrera con puntos para sus respectivos equipos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" class=\"aligncenter size-medium wp-image-9679\" src=\"https:\/\/www.honda.es\/hondadreams\/wp-content\/uploads\/alphatauri-5-600x400.jpg\" alt=\"\" \/><\/p>\n<p>Como de costumbre, Max hizo una salida impecable a toda velocidad, pero su monoplaza sufri\u00f3 un problema en la unidad de potencia que no le permiti\u00f3 correr como acostumbra. Tras caer a media pista, se vio envuelto en un indicente que lo lanz\u00f3 irremedablemente hacia la grava, lo que termin\u00f3 con su jornada de competici\u00f3n y tambi\u00e9n con la del AlphaTauri Pierre Galsy. Al evitar la colisi\u00f3n entre el Ferrari de Charles Leclerc y el Racing Point de Checo P\u00e9rez, Max tuvo que salirse de la pista y perdi\u00f3 el control de su m\u00e1quina.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" class=\"aligncenter size-medium wp-image-9684\" src=\"https:\/\/www.honda.es\/hondadreams\/wp-content\/uploads\/alphatauri2-1-600x400.jpg\" alt=\"\" \/><\/p>\n<p>El neerland\u00e9s no pudo, pues, luchar por la que habr\u00eda sido su segunda victoria de la temporada. El mexicano, sin embargo, s\u00ed que lo consigui\u00f3: Checo se hizo con la fue la primera victoria en la categor\u00eda reina tanto para \u00e9l como para Racing Point.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" class=\"aligncenter size-medium wp-image-9685\" src=\"https:\/\/www.honda.es\/hondadreams\/wp-content\/uploads\/capcalera-2-600x400.jpg\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El piloto de Red Bull Alex Albon consigui\u00f3 cruzar la meta en sexto lugar y&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"class_list":["post-9683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-competicion"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/posts\/9683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/comments?post=9683"}],"version-history":[{"count":2,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/posts\/9683\/revisions"}],"predecessor-version":[{"id":9687,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/posts\/9683\/revisions\/9687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/media\/9678"}],"wp:attachment":[{"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/media?parent=9683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/categories?post=9683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}