{"id":9804,"date":"2021-01-26T16:16:16","date_gmt":"2021-01-26T15:16:16","guid":{"rendered":"https:\/\/www.hondadreams.es\/?p=9804"},"modified":"2021-01-26T16:16:16","modified_gmt":"2021-01-26T15:16:16","slug":"diseno-y-proceso-creativo-el-superpoder-de-honda","status":"publish","type":"post","link":"https:\/\/www.honda.es\/hondadreams\/2021\/01\/26\/diseno-y-proceso-creativo-el-superpoder-de-honda\/","title":{"rendered":"Dise\u00f1o y proceso creativo, el superpoder de Honda"},"content":{"rendered":"<p>Autom\u00f3viles, motocicletas, cortac\u00e9spedes, un avi\u00f3n&#8230; \u00bfAlguna vez te has preguntado c\u00f3mo crea Honda sus <a href=\"https:\/\/www.honda.es\/hondadreams\/2016\/09\/28\/mas-alla-de-la-carretera-5-productos-honda-que-no-son-coches-ni-motos\/\">productos<\/a>? \u00bfDe d\u00f3nde surgen las ideas? A continuaci\u00f3n, revelamos el proceso creativo que constituye la esencia de c\u00f3mo Honda Design, la divisi\u00f3n de dise\u00f1o de la compa\u00f1\u00eda, siembra semillas para obtener la mejor cosecha.<\/p>\n<h3>Investigar el deseo, no la tecnolog\u00eda<\/h3>\n<p>Honda persigue el deseo. Ese ingrediente casi m\u00e1gico que hace que la gente adore sus creaciones. \u00abLa funci\u00f3n del Centro de I + D no es investigar tecnolog\u00eda, sino <strong>investigar lo que le gusta a la gente<\/strong>\u00ab, dijo una vez Soichiro Honda, el fundador de la compa\u00f1\u00eda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" class=\"aligncenter size-medium wp-image-9807\" src=\"https:\/\/www.honda.es\/hondadreams\/wp-content\/uploads\/prototyping-600x338.jpg\" alt=\"\" \/><\/p>\n<p>Todos tenemos sue\u00f1os, esperanzas, pasiones y pasatiempos que mantienen joven nuestro esp\u00edritu. Honda parte de la creencia de que <strong>la curiosidad es la fuente para mejorar la sociedad<\/strong>. Por ello, anima a sus dise\u00f1adores a realizar aquellas actividades que alimentan su sensibilidad creativa. Experimentar, visitar mundos desconocidos, formar parte de algo nuevo, estimula nuestra capacidad de apreciar diferentes entornos sociales, ambientes, olores y sabores&#8230; y esto nos lleva a nuevos descubrimientos o asociaciones de ideas que ponen en cuesti\u00f3n las soluciones existentes.<\/p>\n<h3>Imaginaci\u00f3n sin freno<\/h3>\n<p>Las <a href=\"https:\/\/www.honda.es\/hondadreams\/2019\/03\/27\/el-diseno-en-los-automoviles-honda-como-una-idea-acaba-en-el-mercado\/\">ideas innovadoras<\/a> a menudo pasan por una primera fase de incomprensi\u00f3n. En Honda, es la misi\u00f3n de los dise\u00f1adores<strong> presentar y defender sus visiones y enfoques, por rompedores o incoherentes que puedan parecer<\/strong>. Porque las ideas que se entienden en el momento en que se comparten tienden a estar obsoletas en el momento en que finalmente se lanzan al mercado. La fortaleza de los dise\u00f1adores de Honda es que pueden experimentar visiones y expresarlas libremente. Aunque Honda hace especial hincapi\u00e9 en mantener los pies sobre la tierra y anclar sus nuevas propuestas en base a lo que aportan al mundo y a las personas, y en presentarlas de una forma atractiva y f\u00e1cil de entender para la gran mayor\u00eda.<\/p>\n<h3>El efecto Waigaya<\/h3>\n<p>\u00abWaigaya\u00bb no es una palabra que exista m\u00e1s all\u00e1 de las instalaciones de la compa\u00f1\u00eda: se la invent\u00f3 el socio fundador Takeo Fujisawa, y representa<strong> el ruido de una discusi\u00f3n acalorada, donde las ideas, a menudo en desacuerdo, fluyen de manera ca\u00f3tica<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" class=\"aligncenter size-medium wp-image-9806\" src=\"https:\/\/www.honda.es\/hondadreams\/wp-content\/uploads\/waigaya-600x338.jpg\" alt=\"\" \/><\/p>\n<p>Las herramientas de comunicaci\u00f3n, como el correo electr\u00f3nico y las redes sociales, son pr\u00e1cticas, pero tambi\u00e9n pueden resultar engorrosas e innecesariamente complicadas. A veces, discutir cara a cara es m\u00e1s f\u00e1cil y efectivo. En las ya famosas waigaya de Honda, las ideas se discuten, se expanden, se reenfocan y se llevan a cabo gracias a la suma de las opiniones de todos los dise\u00f1adores.<\/p>\n<h3>Toma un l\u00e1piz<\/h3>\n<p>Consolidada la idea, toca esbozarla. Al dibujar sus ideas y visiones, <strong>los dise\u00f1adores trabajan como los novelistas, artistas y compositores<\/strong>: tan pronto como tienen una idea, la plasman sobre el papel (o cualquier otra superficie, como la palma de su mano), para, fijarla y desarrollarla m\u00e1s tarde. Luego, los modeladores de arcilla determinan la forma tridimensional a partir de bocetos y agregan o raspan arcilla para aclarar las ambig\u00fcedades de los bocetos.<\/p>\n<p>Cada aspecto del producto se considera y se refleja en el modelo de arcilla y los datos 3D, de manera que el dise\u00f1o madura gradualmente. El siguiente paso consiste en la construcci\u00f3n de una maqueta de resina tan realista que para ojos externos es indistinguible del producto real.<\/p>\n<h3>El placer de crear<\/h3>\n<p>Las pruebas en el mundo real siguen siendo imprescindibles. Cuando los prototipos se prueban repetidamente en la vida real, lo inesperado ocurre y se pule el producto. <strong>Los mejores productos surgen de repetidas pruebas y errores<\/strong>. Las maquetas se env\u00edan a los pa\u00edses en los que se vender\u00e1 el producto, para ser inspeccionados por muchos ojos. Tan pronto como la versi\u00f3n detallada de la maqueta est\u00e1 lista, los dise\u00f1adores realizan waigayas con los asociados de ventas y relaciones p\u00fablicas para discutir c\u00f3mo poner en valor las caracter\u00edsticas del producto y qu\u00e9 nombre darle.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"230\" class=\"aligncenter size-medium wp-image-9808\" src=\"https:\/\/www.honda.es\/hondadreams\/wp-content\/uploads\/joy-600x230.jpg\" alt=\"\" \/><\/p>\n<p>En la etapa de fabricaci\u00f3n, dise\u00f1adores y asociados de la f\u00e1brica <strong>perfeccionan la calidad del producto mediante el examen de prototipos de producci\u00f3n en masa<\/strong> y pruebas de precisi\u00f3n. Cuando el producto llega finalmente al cliente, son muchas las personas que han intervenido en el proceso y que sonreir\u00e1n cuando vean que el cliente sonr\u00ede.<\/p>\n<p>Esto es lo que en Honda <strong>se llama el principio de las \u00abtres satisfacciones\u00bb<\/strong>: la \u00absatisfacci\u00f3n de comprar\u00bb de los clientes, la \u00absatisfacci\u00f3n de vender\u00bb de los empleados de ventas y servicios y la \u00absatisfacci\u00f3n de crear\u00bb de los empleados de I + D y fabricaci\u00f3n. Gracias a esta alianza de satisfacciones, se crean productos a la altura de las necesidades y deseos de la sociedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autom\u00f3viles, motocicletas, cortac\u00e9spedes, un avi\u00f3n&#8230; \u00bfAlguna vez te has preguntado c\u00f3mo crea Honda sus productos?&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9805,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"class_list":["post-9804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-honda"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/posts\/9804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/comments?post=9804"}],"version-history":[{"count":2,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/posts\/9804\/revisions"}],"predecessor-version":[{"id":9810,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/posts\/9804\/revisions\/9810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/media\/9805"}],"wp:attachment":[{"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/media?parent=9804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.honda.es\/hondadreams\/wp-json\/wp\/v2\/categories?post=9804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}